{"id":29763,"date":"2020-11-13T12:53:45","date_gmt":"2020-11-13T10:53:45","guid":{"rendered":"https:\/\/es.greenpeace.org\/es\/?post_type=post_documents&#038;p=29763"},"modified":"2020-11-13T12:53:45","modified_gmt":"2020-11-13T10:53:45","slug":"las-cuatro-patas-de-la-campana-hablarural","status":"publish","type":"post_documents","link":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/","title":{"rendered":"Las cuatro patas de la campa\u00f1a #HablaRural:"},"content":{"rendered":"<p>Greenpeace lanza su nueva campa\u00f1a <i>#hablaRural, <\/i>sintetizada en este manifiesto, para que la sociedad espa\u00f1ola comprenda la necesidad urgente de fortalecer nuestro medio rural como prioridad para frenar la p\u00e9rdida de biodiversidad y mitigar la emergencia clim\u00e1tica.<\/p>\n","protected":false},"author":1,"featured_media":29770,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[38,36,35,4],"tags":[],"class_list":["post-29763","post_documents","type-post_documents","status-publish","has-post-thumbnail","hentry","category-agricultura","category-bosques","category-cambio-climatico","category-general"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las cuatro patas de la campa\u00f1a #HablaRural: - ES | Greenpeace Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las cuatro patas de la campa\u00f1a #HablaRural: - ES | Greenpeace Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Greenpeace lanza su nueva campa\u00f1a #hablaRural, sintetizada en este manifiesto, para que la sociedad espa\u00f1ola comprenda la necesidad urgente de fortalecer nuestro medio rural como prioridad para frenar la p\u00e9rdida de biodiversidad y mitigar la emergencia clim\u00e1tica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/\" \/>\n<meta property=\"og:site_name\" content=\"ES | Greenpeace Espa\u00f1a\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/greenpeace.spain\" \/>\n<meta property=\"og:image\" content=\"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2020\/11\/GPES20201111PB0427-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@greenpeace_esp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/sala-de-prensa\\\/documentos\\\/las-cuatro-patas-de-la-campana-hablarural\\\/\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/sala-de-prensa\\\/documentos\\\/las-cuatro-patas-de-la-campana-hablarural\\\/\",\"name\":\"Las cuatro patas de la campa\u00f1a #HablaRural: - ES | Greenpeace Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/sala-de-prensa\\\/documentos\\\/las-cuatro-patas-de-la-campana-hablarural\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/sala-de-prensa\\\/documentos\\\/las-cuatro-patas-de-la-campana-hablarural\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/GPES20201111PB0427-scaled.jpg\",\"datePublished\":\"2020-11-13T10:53:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/sala-de-prensa\\\/documentos\\\/las-cuatro-patas-de-la-campana-hablarural\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/sala-de-prensa\\\/documentos\\\/las-cuatro-patas-de-la-campana-hablarural\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/sala-de-prensa\\\/documentos\\\/las-cuatro-patas-de-la-campana-hablarural\\\/#primaryimage\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/GPES20201111PB0427-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/GPES20201111PB0427-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Silla \u2018Habla Rural\u2019 10\\\/11\\\/2020. Zarzalejos, Espa\u00f1a. Greenpeace, en el marco de su campa\u00f1a #hablaRural, recorre campos, ciudades y pueblos con una silla r\u00fastica para mostrar la necesidad de tener m\u00e1s presente el medio rural y la urgencia de fortalecerlo con el fin de mitigar la crisis clim\u00e1tica y la p\u00e9rdida de biodiversidad. \u00a9Greenpeace\\\/Pablo Bl\u00e1zquez \u00a9Greenpeace Handout\\\/Pablo Bl\u00e1zquez- No sales - No Archives - Editorial Use Only - Free use only for 14 days after release. Photo provided by GREENPEACE, distributed handout photo to be used only to illustrate news reporting or commentary on the facts or events depicted in this image.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/sala-de-prensa\\\/documentos\\\/las-cuatro-patas-de-la-campana-hablarural\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las cuatro patas de la campa\u00f1a #HablaRural:\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/\",\"name\":\"Greenpeace Espa\u00f1a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#organization\",\"name\":\"Greenpeace Espa\u00f1a\",\"alternateName\":\"Greenpeace\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/greenpeace-logo-verde.svg\",\"contentUrl\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/greenpeace-logo-verde.svg\",\"width\":1,\"height\":1,\"caption\":\"Greenpeace Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/greenpeace.spain\",\"https:\\\/\\\/x.com\\\/greenpeace_esp\",\"https:\\\/\\\/www.instagram.com\\\/greenpeace_esp\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las cuatro patas de la campa\u00f1a #HablaRural: - ES | Greenpeace Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/","og_locale":"es_ES","og_type":"article","og_title":"Las cuatro patas de la campa\u00f1a #HablaRural: - ES | Greenpeace Espa\u00f1a","og_description":"Greenpeace lanza su nueva campa\u00f1a #hablaRural, sintetizada en este manifiesto, para que la sociedad espa\u00f1ola comprenda la necesidad urgente de fortalecer nuestro medio rural como prioridad para frenar la p\u00e9rdida de biodiversidad y mitigar la emergencia clim\u00e1tica.","og_url":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/","og_site_name":"ES | Greenpeace Espa\u00f1a","article_publisher":"https:\/\/www.facebook.com\/greenpeace.spain","og_image":[{"width":2560,"height":1707,"url":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2020\/11\/GPES20201111PB0427-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@greenpeace_esp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/","url":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/","name":"Las cuatro patas de la campa\u00f1a #HablaRural: - ES | Greenpeace Espa\u00f1a","isPartOf":{"@id":"https:\/\/es.greenpeace.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/#primaryimage"},"image":{"@id":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/#primaryimage"},"thumbnailUrl":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2020\/11\/GPES20201111PB0427-scaled.jpg","datePublished":"2020-11-13T10:53:45+00:00","breadcrumb":{"@id":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/#primaryimage","url":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2020\/11\/GPES20201111PB0427-scaled.jpg","contentUrl":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2020\/11\/GPES20201111PB0427-scaled.jpg","width":2560,"height":1707,"caption":"Silla \u2018Habla Rural\u2019 10\/11\/2020. Zarzalejos, Espa\u00f1a. Greenpeace, en el marco de su campa\u00f1a #hablaRural, recorre campos, ciudades y pueblos con una silla r\u00fastica para mostrar la necesidad de tener m\u00e1s presente el medio rural y la urgencia de fortalecerlo con el fin de mitigar la crisis clim\u00e1tica y la p\u00e9rdida de biodiversidad. \u00a9Greenpeace\/Pablo Bl\u00e1zquez \u00a9Greenpeace Handout\/Pablo Bl\u00e1zquez- No sales - No Archives - Editorial Use Only - Free use only for 14 days after release. Photo provided by GREENPEACE, distributed handout photo to be used only to illustrate news reporting or commentary on the facts or events depicted in this image."},{"@type":"BreadcrumbList","@id":"https:\/\/es.greenpeace.org\/es\/sala-de-prensa\/documentos\/las-cuatro-patas-de-la-campana-hablarural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/es.greenpeace.org\/es\/"},{"@type":"ListItem","position":2,"name":"Las cuatro patas de la campa\u00f1a #HablaRural:"}]},{"@type":"WebSite","@id":"https:\/\/es.greenpeace.org\/es\/#website","url":"https:\/\/es.greenpeace.org\/es\/","name":"Greenpeace Espa\u00f1a","description":"","publisher":{"@id":"https:\/\/es.greenpeace.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/es.greenpeace.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/es.greenpeace.org\/es\/#organization","name":"Greenpeace Espa\u00f1a","alternateName":"Greenpeace","url":"https:\/\/es.greenpeace.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/es.greenpeace.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2024\/07\/greenpeace-logo-verde.svg","contentUrl":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2024\/07\/greenpeace-logo-verde.svg","width":1,"height":1,"caption":"Greenpeace Espa\u00f1a"},"image":{"@id":"https:\/\/es.greenpeace.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/greenpeace.spain","https:\/\/x.com\/greenpeace_esp","https:\/\/www.instagram.com\/greenpeace_esp\/"]}]}},"_links":{"self":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_documents\/29763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_documents"}],"about":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/types\/post_documents"}],"author":[{"embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_documents\/29763\/revisions"}],"predecessor-version":[{"id":29772,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_documents\/29763\/revisions\/29772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/media\/29770"}],"wp:attachment":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/media?parent=29763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/categories?post=29763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/tags?post=29763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}