{"id":19699,"date":"2019-07-10T17:46:52","date_gmt":"2019-07-10T15:46:52","guid":{"rendered":"https:\/\/es.greenpeace.org\/es\/?post_type=post_profundidad&#038;p=19699"},"modified":"2019-07-10T17:46:52","modified_gmt":"2019-07-10T15:46:52","slug":"un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad","status":"publish","type":"post_profundidad","link":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/","title":{"rendered":"Un \u201cpor si acaso\u201d extra en un contexto de sobrecapacidad"},"content":{"rendered":"<p>Las ayudas permanentes a las centrales de energ\u00eda sucia para que est\u00e9n disponibles son otorgadas independientemente de si generan o no electricidad. Esto se traduce en que, en la pr\u00e1ctica, hay centrales que est\u00e1n totalmente paradas y vierten cero kilovatios a la red.Seg\u00fan datos de Red El\u00e9ctrica Espa\u00f1ola (REE), las centrales de ciclos combinados funcionaron el a\u00f1o pasado el <strong>16,7% de su capacidad total<\/strong>, y las centrales de carb\u00f3n lo hicieron el <strong>56,9% de las horas posibles<\/strong>. La Espa\u00f1a de las infraestructuras fantasma tambi\u00e9n tiene autopistas energ\u00e9ticas por las que no pasa nadie.<\/p>\n<p>Las estimaciones de demanda de ciencia ficci\u00f3n y los permisos descontrolados fueron el c\u00f3ctel perfecto que gener\u00f3 el sobrecoste, la deuda y la sobrecapacidad. La llegada de las renovables no vino acompa\u00f1ada de una sustituci\u00f3n de las energ\u00edas sucias, que se sumaban a \u00e9stas. Con lo cual, en Espa\u00f1a existe un 30% m\u00e1s de capacidad de generaci\u00f3n el\u00e9ctrica de la necesaria para garantizar la cobertura de los picos de demanda. La potencia instalada es de m\u00e1s 104.000 megavatios (MW), y solo en determinados d\u00edas de invierno o verano la demanda supera los 40.000 MW.<\/p>\n","protected":false},"author":44,"featured_media":10955,"parent":19691,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-19699","post_profundidad","type-post_profundidad","status-publish","has-post-thumbnail","hentry","category-cambio-climatico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un \u201cpor si acaso\u201d extra en un contexto de sobrecapacidad - ES | Greenpeace Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un \u201cpor si acaso\u201d extra en un contexto de sobrecapacidad - ES | Greenpeace Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Las ayudas permanentes a las centrales de energ\u00eda sucia para que est\u00e9n disponibles son otorgadas independientemente de si generan o no electricidad. Esto se traduce en que, en la pr\u00e1ctica, hay centrales que est\u00e1n totalmente paradas y vierten cero kilovatios a la red.Seg\u00fan datos de Red El\u00e9ctrica Espa\u00f1ola (REE), las centrales de ciclos combinados funcionaron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"ES | Greenpeace Espa\u00f1a\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/greenpeace.spain\" \/>\n<meta property=\"og:image\" content=\"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/09\/foto-pagos-capacidad-1600-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"889\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@greenpeace_esp\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\\\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\\\/\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\\\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\\\/\",\"name\":\"Un \u201cpor si acaso\u201d extra en un contexto de sobrecapacidad - ES | Greenpeace Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\\\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\\\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/09\\\/foto-pagos-capacidad-1600-1.jpg\",\"datePublished\":\"2019-07-10T15:46:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\\\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\\\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\\\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/09\\\/foto-pagos-capacidad-1600-1.jpg\",\"contentUrl\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/09\\\/foto-pagos-capacidad-1600-1.jpg\",\"width\":1600,\"height\":889,\"caption\":\"Brown coal power station Niederaussem operated by RWE. Built in 1963, this power plant is one of the most polluting in Germany. RWE Braunkohlekraftwerk Niederaussem. Gebaut 1963, gilt dies Kraftwerk wegen seiner hohern CO2 Emissionsrate als das klimaschaedlichste in Deutschland.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\\\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayudas opacas a las energ\u00edas sucias en tu factura\",\"item\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un \u201cpor si acaso\u201d extra en un contexto de sobrecapacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/\",\"name\":\"Greenpeace Espa\u00f1a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#organization\",\"name\":\"Greenpeace Espa\u00f1a\",\"alternateName\":\"Greenpeace\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/greenpeace-logo-verde.svg\",\"contentUrl\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/greenpeace-logo-verde.svg\",\"width\":1,\"height\":1,\"caption\":\"Greenpeace Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/greenpeace.spain\",\"https:\\\/\\\/x.com\\\/greenpeace_esp\",\"https:\\\/\\\/www.instagram.com\\\/greenpeace_esp\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un \u201cpor si acaso\u201d extra en un contexto de sobrecapacidad - ES | Greenpeace Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Un \u201cpor si acaso\u201d extra en un contexto de sobrecapacidad - ES | Greenpeace Espa\u00f1a","og_description":"Las ayudas permanentes a las centrales de energ\u00eda sucia para que est\u00e9n disponibles son otorgadas independientemente de si generan o no electricidad. Esto se traduce en que, en la pr\u00e1ctica, hay centrales que est\u00e1n totalmente paradas y vierten cero kilovatios a la red.Seg\u00fan datos de Red El\u00e9ctrica Espa\u00f1ola (REE), las centrales de ciclos combinados funcionaron [&hellip;]","og_url":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/","og_site_name":"ES | Greenpeace Espa\u00f1a","article_publisher":"https:\/\/www.facebook.com\/greenpeace.spain","og_image":[{"width":1600,"height":889,"url":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/09\/foto-pagos-capacidad-1600-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@greenpeace_esp","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/","url":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/","name":"Un \u201cpor si acaso\u201d extra en un contexto de sobrecapacidad - ES | Greenpeace Espa\u00f1a","isPartOf":{"@id":"https:\/\/es.greenpeace.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/#primaryimage"},"image":{"@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/09\/foto-pagos-capacidad-1600-1.jpg","datePublished":"2019-07-10T15:46:52+00:00","breadcrumb":{"@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/#primaryimage","url":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/09\/foto-pagos-capacidad-1600-1.jpg","contentUrl":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/09\/foto-pagos-capacidad-1600-1.jpg","width":1600,"height":889,"caption":"Brown coal power station Niederaussem operated by RWE. Built in 1963, this power plant is one of the most polluting in Germany. RWE Braunkohlekraftwerk Niederaussem. Gebaut 1963, gilt dies Kraftwerk wegen seiner hohern CO2 Emissionsrate als das klimaschaedlichste in Deutschland."},{"@type":"BreadcrumbList","@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/un-por-si-acaso-extra-en-un-contexto-de-sobrecapacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/es.greenpeace.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ayudas opacas a las energ\u00edas sucias en tu factura","item":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/ayudas-opacas-a-las-energias-sucias-en-tu-factura\/"},{"@type":"ListItem","position":3,"name":"Un \u201cpor si acaso\u201d extra en un contexto de sobrecapacidad"}]},{"@type":"WebSite","@id":"https:\/\/es.greenpeace.org\/es\/#website","url":"https:\/\/es.greenpeace.org\/es\/","name":"Greenpeace Espa\u00f1a","description":"","publisher":{"@id":"https:\/\/es.greenpeace.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/es.greenpeace.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/es.greenpeace.org\/es\/#organization","name":"Greenpeace Espa\u00f1a","alternateName":"Greenpeace","url":"https:\/\/es.greenpeace.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/es.greenpeace.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2024\/07\/greenpeace-logo-verde.svg","contentUrl":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2024\/07\/greenpeace-logo-verde.svg","width":1,"height":1,"caption":"Greenpeace Espa\u00f1a"},"image":{"@id":"https:\/\/es.greenpeace.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/greenpeace.spain","https:\/\/x.com\/greenpeace_esp","https:\/\/www.instagram.com\/greenpeace_esp\/"]}]}},"_links":{"self":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad\/19699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad"}],"about":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/types\/post_profundidad"}],"author":[{"embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/users\/44"}],"version-history":[{"count":2,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad\/19699\/revisions"}],"predecessor-version":[{"id":19701,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad\/19699\/revisions\/19701"}],"up":[{"embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad\/19691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/media\/10955"}],"wp:attachment":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/media?parent=19699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/categories?post=19699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/tags?post=19699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}