{"id":20834,"date":"2019-09-17T12:39:23","date_gmt":"2019-09-17T10:39:23","guid":{"rendered":"https:\/\/es.greenpeace.org\/es\/?post_type=post_profundidad&#038;p=20834"},"modified":"2020-01-15T22:55:09","modified_gmt":"2020-01-15T20:55:09","slug":"ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander","status":"publish","type":"post_profundidad","link":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/","title":{"rendered":"Ruta I: Casi dos a\u00f1os enviando munici\u00f3n fabricada en Burgos a Arabia Saud\u00ed y Emiratos \u00c1rabes desde Bilbao y Santander"},"content":{"rendered":"<div class=\"mb-3 mt-4\">\n<div id=\"videoContainerBurgos\" style=\"width: 100%;\"><\/div>\n<script>\ndocument.addEventListener(\"DOMContentLoaded\", function (t) {\n    var e, o = \"https:\/\/storage.googleapis.com\/gpes-static\/rutas-armas\/RUTA_BURGOS_cuadrado.mp4\", \/\/ Mobile version, small screens\n        a = \"https:\/\/storage.googleapis.com\/gpes-static\/rutas-armas\/RUTA_BURGOS_720.mp4\", \/\/ Desktop, large screens\n        s = document.getElementById(\"videoContainerBurgos\"),\n        r = s.offsetWidth;\n    e = r < 640 ? o : a;\n    var d = document.createElement(\"video\");\n    d.setAttribute(\"controls\", \"controls\"), d.style.maxWidth = \"100%\";\n    var n = document.createElement(\"source\");\n    n.setAttribute(\"src\", e), n.setAttribute(\"type\", \"video\/mp4\"), d.appendChild(n), s.appendChild(d)\n});\n<\/script><br \/>\n<!-- Credit line -->\n<div class=\"clearfix\">\n    <span class=\"float-right\">\n        <a href=\"javascript:void(0);\" data-toggle=\"modal\" data-target=\"#video1Modal\" title=\"Difundir este mapa\" style=\"vertical-align: middle;\" onclick=\"typeof(ga) == 'function' && ga('send', 'event', 'MapaExportacionArmas', 'click', 'Descargar')\">\n            <img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/es-greenpeace-org\/ico\/download.svg\" \/>\n            Descargar\n        <\/a>\n    <\/span>\n<\/div>\n<!-- \/Credit line -->\n<!-- MODAL MAPA -->\n<style>\n    .modal code {\n        font-size: 0.8em;\n        margin-bottom: 1em;\n        background-color: #fff;\n        color: #bbb;\n        display: block;\n        line-height: 1.4em;\n        overflow-wrap: break-word;\n    }\n\n    .modal h4, .modal p, .modal code {\n        text-align: left;\n    }\n<\/style>\n<div class=\"modal fade\" id=\"video1Modal\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"video1ModalLongTitle\" aria-hidden=\"true\">\n    <div class=\"modal-dialog\" role=\"document\">\n        <div class=\"modal-content\">\n            <div class=\"modal-header\">\n                <h3 class=\"modal-title\" id=\"video1ModalLongTitle\">Comparte este v\u00eddeo<\/h3>\n                <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n                    <span aria-hidden=\"true\">&times;<\/span>\n                <\/button>\n            <\/div>\n            <div class=\"modal-body\">\n                \n                <h4>Inserta este v\u00eddeo en tu site<\/h4>\n\n                <p>Inserta este video adaptable en tu site, a\u00f1adiendo el siguiente c\u00f3digo:<\/p>\n\n                <code>&lt;!-- VIDEO --&gt;&lt;div id=\"videoContainerBurgos\" style=\"width: 100%;\"&gt;&lt;\/div&gt;\n&lt;script&gt;\ndocument.addEventListener(\"DOMContentLoaded\", function (t) {\n    var e, o = \"https:\/\/storage.googleapis.com\/gpes-static\/rutas-armas\/RUTA_BURGOS_cuadrado.mp4\",\n        a = \"https:\/\/storage.googleapis.com\/gpes-static\/rutas-armas\/RUTA_BURGOS_720.mp4\",\n        s = document.getElementById(\"videoContainerBurgos\"),\n        r = s.offsetWidth;\n    e = r &lt; 640 ? o : a;\n    var d = document.createElement(\"video\");\n    d.setAttribute(\"controls\", \"controls\"), d.style.maxWidth = \"100%\";\n    var n = document.createElement(\"source\");\n    n.setAttribute(\"src\", e), n.setAttribute(\"type\", \"video\/mp4\"), d.appendChild(n), s.appendChild(d)\n});\n&lt;\/script&gt;&lt;!-- \/VIDEO --&gt;<\/code>\n\n                <p>Ten en cuenta que algunos sites no te dejan a\u00f1adir HTML o Javascript. No podemos dar soporte t\u00e9cnico para insertar este mapa en tu site.<\/p>\n\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<!-- \/MODAL MAPA -->\n\n<\/div>\n<p>El 25 de abril de 2016, un a\u00f1o despu\u00e9s de que estallara la guerra de Yemen, la compa\u00f1\u00eda naviera saud\u00ed Bahri nombraba a Cantabrian Integrated Logistic Services (CILS), del grupo Berg\u00e9, su agente general en Espa\u00f1a que tendr\u00eda <a href=\"https:\/\/bergelogistics.com\/bahri-la-naviera-nacional-de-arabia-saudi-cumple-un-ano-de-operaciones-con-espana\/\" target=\"_blank\" rel=\"noopener noreferrer\">una l\u00ednea regular de carga en el puerto de Bilbao cada 28\/30 d\u00edas<\/a>.<\/p>\n<p>El establecimiento de esta l\u00ednea regular en Bilbao da comienzo a la exportaci\u00f3n continuada de munici\u00f3n bajo el c\u00f3digo arancelario <strong>9306<\/strong>, que corresponde a <strong>\u201cBombas, granadas, torpedos, minas, misiles, y dem\u00e1s municiones y proyectiles\u201d<\/strong> del subtipo <strong>\u201cde guerra\u201d<\/strong>. Entre todo lo enviado, lo que s\u00ed que se ha confirmado a trav\u00e9s de una respuesta del Gobierno a una pregunta parlamentaria es que uno de los env\u00edos consist\u00eda en 17.000 proyectiles completos de artiller\u00eda de 155 mil\u00edmetros.<\/p>\n<p>En total, desde que se tiene conocimiento de la primera exportaci\u00f3n, en octubre de 2016, en las bodegas de esos barcos han navegado con destino a Arabia Saud\u00ed casi 7.000 toneladas de munici\u00f3n<sup><small><a href=\"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/retos-mas-transparencia-y-fin-del-comercio-con-arabia-saudi-e-israel\/#notas\">3<\/a><\/small><\/sup> por un valor cercano a los 120 millones de euros<sup><small><a href=\"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/retos-mas-transparencia-y-fin-del-comercio-con-arabia-saudi-e-israel\/#notas\">4<\/a><\/small><\/sup> (7.514 toneladas de munici\u00f3n y un valor de 138,8 millones de euros si tambi\u00e9n tenemos en cuenta los env\u00edos de munici\u00f3n a Emiratos \u00c1rabes Unidos, que pertenece a la coalici\u00f3n saud\u00ed y participa en la ofensiva contra Yemen).<\/p>\n<p>Todas esta munici\u00f3n se fabric\u00f3 y distribuy\u00f3 desde las instalaciones que la empresa Expal Systems, perteneciente al Grupo Maxam, tiene en Quintanilla de Sobresierra (Burgos). Desde all\u00ed se env\u00edan hasta el puerto donde se realizar\u00e1 la carga en los buques a trav\u00e9s de convoyes de camiones escoltados por empresas de seguridad y por la Guardia Civil.<\/p>\n<p>Una de las curiosidades de este caso y que a la vez es un ejemplo de las dudosas pr\u00e1cticas del sector armament\u00edstico, es c\u00f3mo la naviera saud\u00ed ha tratado de ocultar sistem\u00e1ticamente las operaciones realizadas desde Espa\u00f1a a medida que empez\u00f3 a aumentar la presi\u00f3n social contra el env\u00edo de armas espa\u00f1olas a Arabia Saud\u00ed y Emiratos \u00c1rabes Unidos. Todo debido a la negativa de un <a href=\"https:\/\/www.youtube.com\/watch?v=se8IUxsupTc\" target=\"_blank\" rel=\"noopener noreferrer\">bombero de Vizcaya<\/a>  a participar en el ret\u00e9n que vigilaba la carga en el puerto de Bilbao al conocer su destino y haber sido informado de que \u201ceran bombas\u201d. La primera medida de la naviera Bahri fue ocultar destinos espa\u00f1oles en su <a href=\"\/wp-content\/uploads\/sites\/3\/2018\/09\/site-desarme.jpg\">p\u00e1gina web<\/a>.<\/p>\n<p>Posteriormente trataron de ocultar los logos de sus barcos, como muestran las siguientes fotograf\u00edas de las visitas del buque Bahri Jeddah a Bilbao en junio y diciembre de 2017:<\/p>\n<!-- ADD JUST ONCE -->\n<link rel=\"stylesheet\" type=\"text\/css\" href=\"https:\/\/storage.googleapis.com\/gpes-static\/libs\/css\/ab.min.css\" \/>\n\n<!-- SET THE IMAGES HERE -->\n<div class=\"ba-slider\">\n    <img decoding=\"async\" id=\"ab_image1\" src=\"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2019\/09\/bahri-junio-17.jpg\" alt=\"\">\n    <div class=\"resize\">\n        <img decoding=\"async\" id=\"ab_image2\" src=\"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2019\/09\/bahri-diciembre-17.jpg\" alt=\"\">\n    <\/div>\n    <span class=\"handle\"><\/span>\n<\/div>\n\n<!-- ADD JUST ONCE -->\n<script src=\"https:\/\/storage.googleapis.com\/gpes-static\/libs\/js\/ab.min.js\" defer><\/script>\n\n<p>Adem\u00e1s, en varias ocasiones, han puesto rumbo a puertos espa\u00f1oles desconectando el Sistema de Identificaci\u00f3n Autom\u00e1tica Mar\u00edtima, con el que est\u00e1n obligados a navegar por cuestiones de seguridad, para impedir que se pueda rastrear su navegaci\u00f3n y puerto de destino. Esta deficiencia fue detectada en inspecciones realizadas al <em>Bahri Tabuk<\/em> en Bilbao el 21 de septiembre de 2017 y al <em>Bahri Hofuf<\/em> en Santander el 8 de marzo de 2018. <\/p>\n<p>Finalmente, y muy probablemente en un intento de desplazar la atenci\u00f3n de los diferentes colectivos que han denunciado el caso y demandado el fin de la venta de armas a estos pa\u00edses de la coalici\u00f3n saud\u00ed, las operaciones de carga de los buques Bahri fue desplazada al puerto de Santander, desde donde se han realizado los \u00faltimos env\u00edos.<\/p>\n","protected":false},"author":44,"featured_media":5416,"parent":20828,"menu_order":1,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[39],"tags":[],"class_list":["post-20834","post_profundidad","type-post_profundidad","status-publish","has-post-thumbnail","hentry","category-desarme-y-paz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ruta I: Casi dos a\u00f1os enviando munici\u00f3n fabricada en Burgos a Arabia Saud\u00ed y Emiratos \u00c1rabes desde Bilbao y Santander - ES | Greenpeace Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ruta I: Casi dos a\u00f1os enviando munici\u00f3n fabricada en Burgos a Arabia Saud\u00ed y Emiratos \u00c1rabes desde Bilbao y Santander - ES | Greenpeace Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"El 25 de abril de 2016, un a\u00f1o despu\u00e9s de que estallara la guerra de Yemen, la compa\u00f1\u00eda naviera saud\u00ed Bahri nombraba a Cantabrian Integrated Logistic Services (CILS), del grupo Berg\u00e9, su agente general en Espa\u00f1a que tendr\u00eda una l\u00ednea regular de carga en el puerto de Bilbao cada 28\/30 d\u00edas. El establecimiento de esta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/\" \/>\n<meta property=\"og:site_name\" content=\"ES | Greenpeace Espa\u00f1a\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/greenpeace.spain\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-15T20:55:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/02\/GPES20180216SB-0034-e1518810559629.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@greenpeace_esp\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/las-rutas-de-riesgo-de-las-armas-espanolas\\\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\\\/\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/las-rutas-de-riesgo-de-las-armas-espanolas\\\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\\\/\",\"name\":\"Ruta I: Casi dos a\u00f1os enviando munici\u00f3n fabricada en Burgos a Arabia Saud\u00ed y Emiratos \u00c1rabes desde Bilbao y Santander - ES | Greenpeace Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/las-rutas-de-riesgo-de-las-armas-espanolas\\\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/las-rutas-de-riesgo-de-las-armas-espanolas\\\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/02\\\/GPES20180216SB-0034-e1518810559629.jpg\",\"datePublished\":\"2019-09-17T10:39:23+00:00\",\"dateModified\":\"2020-01-15T20:55:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/las-rutas-de-riesgo-de-las-armas-espanolas\\\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/las-rutas-de-riesgo-de-las-armas-espanolas\\\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/las-rutas-de-riesgo-de-las-armas-espanolas\\\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\\\/#primaryimage\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/02\\\/GPES20180216SB-0034-e1518810559629.jpg\",\"contentUrl\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/02\\\/GPES20180216SB-0034-e1518810559629.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9Greenpeace\\\/Santi Burgos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/las-rutas-de-riesgo-de-las-armas-espanolas\\\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las rutas de riesgo de las armas espa\u00f1olas\",\"item\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/en-profundidad\\\/las-rutas-de-riesgo-de-las-armas-espanolas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ruta I: Casi dos a\u00f1os enviando munici\u00f3n fabricada en Burgos a Arabia Saud\u00ed y Emiratos \u00c1rabes desde Bilbao y Santander\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/\",\"name\":\"Greenpeace Espa\u00f1a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#organization\",\"name\":\"Greenpeace Espa\u00f1a\",\"alternateName\":\"Greenpeace\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/greenpeace-logo-verde.svg\",\"contentUrl\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/07\\\/greenpeace-logo-verde.svg\",\"width\":1,\"height\":1,\"caption\":\"Greenpeace Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/es.greenpeace.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/greenpeace.spain\",\"https:\\\/\\\/x.com\\\/greenpeace_esp\",\"https:\\\/\\\/www.instagram.com\\\/greenpeace_esp\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ruta I: Casi dos a\u00f1os enviando munici\u00f3n fabricada en Burgos a Arabia Saud\u00ed y Emiratos \u00c1rabes desde Bilbao y Santander - ES | Greenpeace Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/","og_locale":"es_ES","og_type":"article","og_title":"Ruta I: Casi dos a\u00f1os enviando munici\u00f3n fabricada en Burgos a Arabia Saud\u00ed y Emiratos \u00c1rabes desde Bilbao y Santander - ES | Greenpeace Espa\u00f1a","og_description":"El 25 de abril de 2016, un a\u00f1o despu\u00e9s de que estallara la guerra de Yemen, la compa\u00f1\u00eda naviera saud\u00ed Bahri nombraba a Cantabrian Integrated Logistic Services (CILS), del grupo Berg\u00e9, su agente general en Espa\u00f1a que tendr\u00eda una l\u00ednea regular de carga en el puerto de Bilbao cada 28\/30 d\u00edas. El establecimiento de esta [&hellip;]","og_url":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/","og_site_name":"ES | Greenpeace Espa\u00f1a","article_publisher":"https:\/\/www.facebook.com\/greenpeace.spain","article_modified_time":"2020-01-15T20:55:09+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/02\/GPES20180216SB-0034-e1518810559629.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@greenpeace_esp","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/","url":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/","name":"Ruta I: Casi dos a\u00f1os enviando munici\u00f3n fabricada en Burgos a Arabia Saud\u00ed y Emiratos \u00c1rabes desde Bilbao y Santander - ES | Greenpeace Espa\u00f1a","isPartOf":{"@id":"https:\/\/es.greenpeace.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/#primaryimage"},"image":{"@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/#primaryimage"},"thumbnailUrl":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/02\/GPES20180216SB-0034-e1518810559629.jpg","datePublished":"2019-09-17T10:39:23+00:00","dateModified":"2020-01-15T20:55:09+00:00","breadcrumb":{"@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/#primaryimage","url":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/02\/GPES20180216SB-0034-e1518810559629.jpg","contentUrl":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2018\/02\/GPES20180216SB-0034-e1518810559629.jpg","width":1200,"height":800,"caption":"\u00a9Greenpeace\/Santi Burgos"},{"@type":"BreadcrumbList","@id":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/ruta-i-casi-dos-anos-enviando-municion-fabricada-en-burgos-a-arabia-saudi-y-emiratos-arabes-desde-bilbao-y-santander\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/es.greenpeace.org\/es\/"},{"@type":"ListItem","position":2,"name":"Las rutas de riesgo de las armas espa\u00f1olas","item":"https:\/\/es.greenpeace.org\/es\/en-profundidad\/las-rutas-de-riesgo-de-las-armas-espanolas\/"},{"@type":"ListItem","position":3,"name":"Ruta I: Casi dos a\u00f1os enviando munici\u00f3n fabricada en Burgos a Arabia Saud\u00ed y Emiratos \u00c1rabes desde Bilbao y Santander"}]},{"@type":"WebSite","@id":"https:\/\/es.greenpeace.org\/es\/#website","url":"https:\/\/es.greenpeace.org\/es\/","name":"Greenpeace Espa\u00f1a","description":"","publisher":{"@id":"https:\/\/es.greenpeace.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/es.greenpeace.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/es.greenpeace.org\/es\/#organization","name":"Greenpeace Espa\u00f1a","alternateName":"Greenpeace","url":"https:\/\/es.greenpeace.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/es.greenpeace.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2024\/07\/greenpeace-logo-verde.svg","contentUrl":"https:\/\/es.greenpeace.org\/es\/wp-content\/uploads\/sites\/3\/2024\/07\/greenpeace-logo-verde.svg","width":1,"height":1,"caption":"Greenpeace Espa\u00f1a"},"image":{"@id":"https:\/\/es.greenpeace.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/greenpeace.spain","https:\/\/x.com\/greenpeace_esp","https:\/\/www.instagram.com\/greenpeace_esp\/"]}]}},"_links":{"self":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad\/20834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad"}],"about":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/types\/post_profundidad"}],"author":[{"embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/users\/44"}],"version-history":[{"count":10,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad\/20834\/revisions"}],"predecessor-version":[{"id":23310,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad\/20834\/revisions\/23310"}],"up":[{"embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/post_profundidad\/20828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/media\/5416"}],"wp:attachment":[{"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/media?parent=20834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/categories?post=20834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/es.greenpeace.org\/es\/wp-json\/wp\/v2\/tags?post=20834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}